{"id":337,"date":"2025-09-01T13:05:39","date_gmt":"2025-09-01T13:05:39","guid":{"rendered":"https:\/\/conex-5.hipdev.pro\/?page_id=337"},"modified":"2025-09-01T13:59:46","modified_gmt":"2025-09-01T13:59:46","slug":"career","status":"publish","type":"page","link":"https:\/\/conex-5.hipdev.pro\/fr\/career\/","title":{"rendered":"Carri\u00e8re"},"content":{"rendered":"<section class=\"page-hero2-section\" style=\"background-image: url(https:\/\/conex-5.hipdev.pro\/wp-content\/uploads\/2025\/09\/image41-scaled.webp);\">\r\n    <div class=\"container\">\r\n        <div class=\"row align-items-end half-height\">\r\n            <div class=\"col-lg-10\">\r\n                <div class=\"section-title\"><h6>Carri\u00e8re<\/h6><h1>TRAVAILLER AVEC NOUS<\/h1><p>Si vous \u00eates passionn\u00e9 par l'humain, si vous vivez et respirez la technologie, et si vous aimez r\u00e9soudre des d\u00e9fis complexes en reliant les points.... Postulez maintenant et rejoignez l'\u00e9quipe !\u00a0<\/p><\/div>            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\n\n<section class=\"jobs-section\" id=\"\">\r\n    <div class=\"container\">\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n                <div class=\"job-box\"><h3>POSITION DE TRAVAIL<\/h3><p>Si vous \u00eates passionn\u00e9 par l'humain, si vous vivez et respirez la technologie, et si vous aimez r\u00e9soudre des d\u00e9fis complexes en reliant les points.... Postulez maintenant et rejoignez l'\u00e9quipe !\u00a0<\/p>\n<ul><li class=\"work\">Temps plein<\/li><li class=\"loc\">Localisation<\/li><\/ul><a class=\"c-btn light-btn\" href=\"#\" target=\"_self\">Appliquer \u2192<\/a><\/div><div class=\"job-box\"><h3>POSITION DE TRAVAIL<\/h3><p>Si vous \u00eates passionn\u00e9 par l'humain, si vous vivez et respirez la technologie, et si vous aimez r\u00e9soudre des d\u00e9fis complexes en reliant les points.... Postulez maintenant et rejoignez l'\u00e9quipe !\u00a0<\/p>\n<ul><li class=\"work\">Temps plein<\/li><li class=\"loc\">Localisation<\/li><\/ul><a class=\"c-btn light-btn\" href=\"#\" target=\"_self\">Appliquer \u2192<\/a><\/div><div class=\"job-box\"><h3>POSITION DE TRAVAIL<\/h3><p>Si vous \u00eates passionn\u00e9 par l'humain, si vous vivez et respirez la technologie, et si vous aimez r\u00e9soudre des d\u00e9fis complexes en reliant les points.... Postulez maintenant et rejoignez l'\u00e9quipe !\u00a0<\/p>\n<ul><li class=\"work\">Temps plein<\/li><li class=\"loc\">Localisation<\/li><\/ul><a class=\"c-btn light-btn\" href=\"#\" target=\"_self\">Appliquer \u2192<\/a><\/div><div class=\"job-box\"><h3>POSITION DE TRAVAIL<\/h3><p>Si vous \u00eates passionn\u00e9 par l'humain, si vous vivez et respirez la technologie, et si vous aimez r\u00e9soudre des d\u00e9fis complexes en reliant les points.... Postulez maintenant et rejoignez l'\u00e9quipe !\u00a0<\/p>\n<ul><li class=\"work\">Temps plein<\/li><li class=\"loc\">Localisation<\/li><\/ul><a class=\"c-btn light-btn\" href=\"#\" target=\"_self\">Appliquer \u2192<\/a><\/div><div class=\"job-box\"><h3>POSITION DE TRAVAIL<\/h3><p>Si vous \u00eates passionn\u00e9 par l'humain, si vous vivez et respirez la technologie, et si vous aimez r\u00e9soudre des d\u00e9fis complexes en reliant les points.... Postulez maintenant et rejoignez l'\u00e9quipe !\u00a0<\/p>\n<ul><li class=\"work\">Temps plein<\/li><li class=\"loc\">Localisation<\/li><\/ul><a class=\"c-btn light-btn\" href=\"#\" target=\"_self\">Appliquer \u2192<\/a><\/div>            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-337","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/conex-5.hipdev.pro\/fr\/wp-json\/wp\/v2\/pages\/337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conex-5.hipdev.pro\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/conex-5.hipdev.pro\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/conex-5.hipdev.pro\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conex-5.hipdev.pro\/fr\/wp-json\/wp\/v2\/comments?post=337"}],"version-history":[{"count":0,"href":"https:\/\/conex-5.hipdev.pro\/fr\/wp-json\/wp\/v2\/pages\/337\/revisions"}],"wp:attachment":[{"href":"https:\/\/conex-5.hipdev.pro\/fr\/wp-json\/wp\/v2\/media?parent=337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}